{"id":7386,"date":"2019-03-10T16:08:07","date_gmt":"2019-03-10T15:08:07","guid":{"rendered":"https:\/\/www.lesgarszellesfontenoises.fr\/?p=7386"},"modified":"2019-03-10T16:08:28","modified_gmt":"2019-03-10T15:08:28","slug":"le-trefle-a-4-feuilles-2019","status":"publish","type":"post","link":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/2019\/03\/10\/le-trefle-a-4-feuilles-2019\/","title":{"rendered":"Le tr\u00eafle \u00e0 4 feuilles 2019."},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-1.jpg\" alt=\"\" class=\"wp-image-7363\" width=\"346\" height=\"260\" srcset=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-1.jpg 1024w, https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-1-300x225.jpg 300w, https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-1-768x576.jpg 768w, https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-1-360x270.jpg 360w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/><\/figure><\/div>\n\n\n\n<p>Ce dimanche, les Gars\u2019Z\u2019Elles se sont d\u00e9plac\u00e9es chez nos voisins de Vivonne pour l\u2019\u00e9dition 2019 du Tr\u00eafle \u00e0 4 feuilles.<\/p>\n\n\n\n<p>Au programme, 7, 13 et 23,5 km avec une m\u00e9t\u00e9o \u00e0 peu pr\u00e8s cl\u00e9mente&nbsp;!!!!<\/p>\n\n\n\n<p>Superbe organisation et supers parcours&nbsp;!!!!!<\/p>\n\n\n\n<p>F\u00e9licitations \u00e0 toutes et \u00e0 tous et rendez vous l\u2019ann\u00e9e prochaine.<\/p>\n\n\n\n<p>(Merci \u00e0 Vivonne Loisirs pour les photos&nbsp;!!!!)<\/p>\n\n\n<div id=\"Block_wpape_gallery_6a04cb91de37f\" style=\"width:100%;padding-left:5px;padding-top:5px;padding-right:5px;padding-bottom:5px; display: none;\"><div class=\"wpape_gallery_button wpape_gallery_align_left\"  id=\"wpape_gallery_6a04cb91de37ffilter\"><a class=\" apebtn apebtn-flat apebtn-primary  active\" style=\"margin-right:5px;margin-bottom:10px;\" href=\"#\" data-filter=\"*\">Home<\/a><a href=\"#\" data-filter=\".category7362\" class=\" apebtn apebtn-flat apebtn-primary \" style=\"margin-right:5px;margin-bottom:10px;\">2019.03.10 Course Tr\u00e8fle Vivonne 2019<\/a><\/div><div id=\"wpape_gallery_6a04cb91de37f\" data-options=\"wpape_gallery_6a04cb91de37f\" style=\"width:100%;\" class=\"wpape_gallery\"><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-1-300x225.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (1)\" data-width=\"300\" data-height=\"225\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-1.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (1)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (1)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-2-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (2)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-2.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (2)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (2)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-3-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (3)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-3.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (3)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (3)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-4-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (4)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-4.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (4)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (4)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-5-300x200.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (5)\" data-width=\"300\" data-height=\"200\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-5.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (5)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (5)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-6-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (6)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-6.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (6)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (6)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-7-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (7)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-7.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (7)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (7)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-8-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (8)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-8.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (8)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (8)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-9-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (9)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-9.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (9)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (9)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-10-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (10)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-10.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (10)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (10)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-11-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (11)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-11.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (11)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (11)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-12-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (12)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-12.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (12)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (12)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-13-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (13)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-13.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (13)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (13)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-14-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (14)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-14.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (14)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (14)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-15-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (15)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-15.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (15)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (15)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-16-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (16)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-16.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (16)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (16)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-17-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (17)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-17.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (17)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (17)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-18-200x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (18)\" data-width=\"200\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-18.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (18)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (18)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-19-223x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (19)\" data-width=\"223\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-19.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (19)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (19)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-20-156x300.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (20)\" data-width=\"156\" data-height=\"300\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-20.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (20)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (20)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-21-300x200.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (21)\" data-width=\"300\" data-height=\"200\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-21.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (21)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (21)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-22-300x200.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (22)\" data-width=\"300\" data-height=\"200\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-22.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (22)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (22)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"wpape-img category7362\" ><div class=\"wpape-img-image  wpape-lightbox\"  ><div data-thumbnail=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-23-300x200.jpg\" title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (23)\" data-width=\"300\" data-height=\"200\" ><\/div><div data-popup=\"https:\/\/www.lesgarszellesfontenoises.fr\/wp-content\/uploads\/2019\/03\/2019.03.10-Trefles_4_feuilles_vivonne_2019_-23.jpg\"  title=\"2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (23)\"><\/div><div class=\"thumbnail-overlay\"><div class=\"wpapeTitle \">2019.03.10 Tr\u00e8fles_4_feuilles_vivonne_2019_ (23)<\/div><div class=\"wpapeIcons\"><i class=\"fa fa-search wpapeZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><\/div><\/div><script>var wpape_gallery_6a04cb91de37f = {\"filterContainer\": \"#wpape_gallery_6a04cb91de37ffilter\", \"touch\": 1, \"columns\": 3, \"columnWidth\": \"auto\", \"resolutions\": [ ,  , ], \"overlayEffect\": \"direction-aware-fade\", \"boxesToLoadStart\": \"9\", \"boxesToLoad\": \"6\", \"lazyLoad\": true, \"LoadingWord\": \"Gallery images loading\", \"loadMoreWord\": \"More images\", \"noMoreEntriesWord\": \"No images\", \"loadMoreClass\": \" apebtn apebtn-flat apebtn-primary \", \"horizontalSpaceBetweenBoxes\": 10, \"verticalSpaceBetweenBoxes\": 10}, wpape_gallery_6a04cb91de37f_css = \"body .mfp-ready.mfp-bg{background-color: rgba(11,11,11,0.8);}.mfp-container .mfp-arrow{display:none;}#wpape_gallery_6a04cb91de37f .wpape-img-container{ -webkit-border-radius: 5px;-moz-border-radius: 5px;border-radius: 5px;}#wpape_gallery_6a04cb91de37f .wpapeTitle{ font-size:12px; line-height:88%; color:#ffffff;}#wpape_gallery_6a04cb91de37f .wpapeTitle:hover{color:#ffffff;}#wpape_gallery_6a04cb91de37f .thumbnail-overlay{background:rgba(7,7,7,0.5);}#wpape_gallery_6a04cb91de37f .wpapeZoomIcon{ font-size:22px; line-height:100%; color:#ffffff;background:rgba(0,0,0,0);}#wpape_gallery_6a04cb91de37f .wpapeZoomIcon:hover{color:#ffffff;background:rgba(0,0,0,0);}#wpape_gallery_6a04cb91de37f .image-with-dimensions{background-color: rgba(255,255,255,1);}body .mfp-title, body .mfp-counter{color: rgb(243,243,243);}\",apeGalleryDelay = 0; head = document.head || document.getElementsByTagName(\"head\")[0], style = document.createElement(\"style\"); style.type = \"text\/css\"; if (style.styleSheet) style.styleSheet.cssText = wpape_gallery_6a04cb91de37f_css; \telse  style.appendChild(document.createTextNode(wpape_gallery_6a04cb91de37f_css)); head.appendChild(style);<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Ce dimanche, les Gars\u2019Z\u2019Elles se sont d\u00e9plac\u00e9es chez nos voisins de Vivonne pour l\u2019\u00e9dition 2019 du Tr\u00eafle \u00e0 4 feuilles. Au programme, 7, 13 et 23,5 km avec une m\u00e9t\u00e9o \u00e0 peu pr\u00e8s cl\u00e9mente&nbsp;!!!! Superbe organisation et supers parcours&nbsp;!!!!! F\u00e9licitations \u00e0 toutes et \u00e0 tous et rendez vous l\u2019ann\u00e9e prochaine. (Merci \u00e0 Vivonne Loisirs pour les photos&nbsp;!!!!)<\/p>\n","protected":false},"author":1,"featured_media":7363,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-7386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sorties-2019"],"_links":{"self":[{"href":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/wp-json\/wp\/v2\/posts\/7386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/wp-json\/wp\/v2\/comments?post=7386"}],"version-history":[{"count":2,"href":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/wp-json\/wp\/v2\/posts\/7386\/revisions"}],"predecessor-version":[{"id":7388,"href":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/wp-json\/wp\/v2\/posts\/7386\/revisions\/7388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/wp-json\/wp\/v2\/media\/7363"}],"wp:attachment":[{"href":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/wp-json\/wp\/v2\/media?parent=7386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/wp-json\/wp\/v2\/categories?post=7386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesgarszellesfontenoises.fr\/index.php\/wp-json\/wp\/v2\/tags?post=7386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}